{"id":3249,"date":"2010-08-28T08:28:49","date_gmt":"2010-08-28T15:28:49","guid":{"rendered":"http:\/\/bassic-sax.info\/version5\/?page_id=3249"},"modified":"2013-01-11T11:17:56","modified_gmt":"2013-01-11T18:17:56","slug":"impala","status":"publish","type":"page","link":"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/european-made-saxes\/dorfler-jorka\/dj-stencil-galleries\/impala\/","title":{"rendered":"Impala"},"content":{"rendered":"<p><span style=\"font-size: 22px;\">Impala Tenor<\/span><\/p>\n<p>Serial #: 16376<br \/>\nFinish: Silver plated<\/p>\nngg_shortcode_0_placeholder\n<p><span style=\"font-size: 10px;\">\u00a0 Source: eBay.de<\/span><\/p>\n<p>If you are interested in the Impala stencil saxophones made by D\u00f6rfler &amp; J\u00f6rka, then be sure to check out the <a href=\"http:\/\/bassic-sax.info\/4images\/categories.php?cat_id=453\" target=\"_blank\">Impala gallery on Bassic Sax Pix<\/a>. There you will find an alto that was sold by one of my favourite eBay dealers, <a href=\"http:\/\/myworld.ebay.com\/the_little_sax_shop\/\" target=\"_blank\">The Little Sax Shop<\/a>. Mark Wiseman is a professional player who deals in high quality, vintage, and used pro horns on eBay.<\/p>\n<p>The <a href=\"http:\/\/bassic-sax.info\/4images\/categories.php?cat_id=991\" target=\"_blank\">Impala alto that Mark sold<\/a> was in remarkable condition, and like the tenor shown on this page, is silver plated. It is worth noting that of the hundreds of D&amp;J saxophones that I have seen to date, only a handful have been silver-plated. The rest are either two tone (lacquer with nickel plated keys), or lacquered.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Impala Tenor Serial #: 16376 Finish: Silver plated \u00a0 Source: eBay.de If you are interested in the Impala stencil saxophones made by D\u00f6rfler &amp; J\u00f6rka,&hellip;<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":1107,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-3249","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Impala, D\u00f6rfler &amp; J\u00f6rka, D&amp;J German-made, stencil saxophone, alto sax, tenor sax, vintage saxophone, Keilwerth clone horn, not a JK stencil sax!\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/european-made-saxes\/dorfler-jorka\/dj-stencil-galleries\/impala\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bassic-sax.info\\\/version5\\\/vintage-saxes\\\/european-made-saxes\\\/dorfler-jorka\\\/dj-stencil-galleries\\\/impala\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bassic-sax.info\\\/version5#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bassic-sax.info\\\/version5\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bassic-sax.info\\\/version5\\\/vintage-saxes\\\/#listItem\",\"name\":\"Vintage Saxes\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bassic-sax.info\\\/version5\\\/vintage-saxes\\\/#listItem\",\"position\":2,\"name\":\"Vintage Saxes\",\"item\":\"https:\\\/\\\/bassic-sax.info\\\/version5\\\/vintage-saxes\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bassic-sax.info\\\/version5\\\/vintage-saxes\\\/european-made-saxes\\\/#listItem\",\"name\":\"European-Made Saxes\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bassic-sax.info\\\/version5#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bassic-sax.info\\\/version5\\\/vintage-saxes\\\/european-made-saxes\\\/#listItem\",\"position\":3,\"name\":\"European-Made Saxes\",\"item\":\"https:\\\/\\\/bassic-sax.info\\\/version5\\\/vintage-saxes\\\/european-made-saxes\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bassic-sax.info\\\/version5\\\/vintage-saxes\\\/european-made-saxes\\\/dorfler-jorka\\\/#listItem\",\"name\":\"D\\u00f6rfler &#038; J\\u00f6rka\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bassic-sax.info\\\/version5\\\/vintage-saxes\\\/#listItem\",\"name\":\"Vintage Saxes\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bassic-sax.info\\\/version5\\\/vintage-saxes\\\/european-made-saxes\\\/dorfler-jorka\\\/#listItem\",\"position\":4,\"name\":\"D\\u00f6rfler &#038; J\\u00f6rka\",\"item\":\"https:\\\/\\\/bassic-sax.info\\\/version5\\\/vintage-saxes\\\/european-made-saxes\\\/dorfler-jorka\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bassic-sax.info\\\/version5\\\/vintage-saxes\\\/european-made-saxes\\\/dorfler-jorka\\\/dj-stencil-galleries\\\/#listItem\",\"name\":\"D&#038;J Stencil Galleries\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bassic-sax.info\\\/version5\\\/vintage-saxes\\\/european-made-saxes\\\/#listItem\",\"name\":\"European-Made Saxes\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bassic-sax.info\\\/version5\\\/vintage-saxes\\\/european-made-saxes\\\/dorfler-jorka\\\/dj-stencil-galleries\\\/#listItem\",\"position\":5,\"name\":\"D&#038;J Stencil Galleries\",\"item\":\"https:\\\/\\\/bassic-sax.info\\\/version5\\\/vintage-saxes\\\/european-made-saxes\\\/dorfler-jorka\\\/dj-stencil-galleries\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bassic-sax.info\\\/version5\\\/vintage-saxes\\\/european-made-saxes\\\/dorfler-jorka\\\/dj-stencil-galleries\\\/impala\\\/#listItem\",\"name\":\"Impala\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bassic-sax.info\\\/version5\\\/vintage-saxes\\\/european-made-saxes\\\/dorfler-jorka\\\/#listItem\",\"name\":\"D\\u00f6rfler &#038; J\\u00f6rka\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bassic-sax.info\\\/version5\\\/vintage-saxes\\\/european-made-saxes\\\/dorfler-jorka\\\/dj-stencil-galleries\\\/impala\\\/#listItem\",\"position\":6,\"name\":\"Impala\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bassic-sax.info\\\/version5\\\/vintage-saxes\\\/european-made-saxes\\\/dorfler-jorka\\\/dj-stencil-galleries\\\/#listItem\",\"name\":\"D&#038;J Stencil Galleries\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bassic-sax.info\\\/version5\\\/#organization\",\"name\":\"Bassic Sax Studios\",\"description\":\"Bassically A Site About All Things Sax\",\"url\":\"https:\\\/\\\/bassic-sax.info\\\/version5\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/bassic-sax.info\\\/version5\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Bassic-Sax-Logo-2025-500px.png?fit=500%2C500&ssl=1\",\"@id\":\"https:\\\/\\\/bassic-sax.info\\\/version5\\\/vintage-saxes\\\/european-made-saxes\\\/dorfler-jorka\\\/dj-stencil-galleries\\\/impala\\\/#organizationLogo\",\"width\":500,\"height\":500,\"caption\":\"Bassic Sax log, transparent background, blue circle around blue triangle with two bass saxophones entwined around each other, Bassic Sax in a bold sans font typed under the base of the triangle\"},\"image\":{\"@id\":\"https:\\\/\\\/bassic-sax.info\\\/version5\\\/vintage-saxes\\\/european-made-saxes\\\/dorfler-jorka\\\/dj-stencil-galleries\\\/impala\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/bassic.sax.blog.and.jazz.ensemble\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bassic-sax.info\\\/version5\\\/vintage-saxes\\\/european-made-saxes\\\/dorfler-jorka\\\/dj-stencil-galleries\\\/impala\\\/#webpage\",\"url\":\"https:\\\/\\\/bassic-sax.info\\\/version5\\\/vintage-saxes\\\/european-made-saxes\\\/dorfler-jorka\\\/dj-stencil-galleries\\\/impala\\\/\",\"name\":\"Impala - Bassic Sax | Bassic Sax\",\"description\":\"Impala, D\\u00f6rfler & J\\u00f6rka, D&J German-made, stencil saxophone, alto sax, tenor sax, vintage saxophone, Keilwerth clone horn, not a JK stencil sax!\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bassic-sax.info\\\/version5\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bassic-sax.info\\\/version5\\\/vintage-saxes\\\/european-made-saxes\\\/dorfler-jorka\\\/dj-stencil-galleries\\\/impala\\\/#breadcrumblist\"},\"datePublished\":\"2010-08-28T08:28:49-07:00\",\"dateModified\":\"2013-01-11T11:17:56-08:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bassic-sax.info\\\/version5\\\/#website\",\"url\":\"https:\\\/\\\/bassic-sax.info\\\/version5\\\/\",\"name\":\"Bassic Sax\",\"description\":\"Bassically A Site About All Things Sax\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/bassic-sax.info\\\/version5\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Impala - Bassic Sax | Bassic Sax","description":"Impala, D\u00f6rfler & J\u00f6rka, D&J German-made, stencil saxophone, alto sax, tenor sax, vintage saxophone, Keilwerth clone horn, not a JK stencil sax!","canonical_url":"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/european-made-saxes\/dorfler-jorka\/dj-stencil-galleries\/impala\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/european-made-saxes\/dorfler-jorka\/dj-stencil-galleries\/impala\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/bassic-sax.info\/version5#listItem","position":1,"name":"Home","item":"https:\/\/bassic-sax.info\/version5","nextItem":{"@type":"ListItem","@id":"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/#listItem","name":"Vintage Saxes"}},{"@type":"ListItem","@id":"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/#listItem","position":2,"name":"Vintage Saxes","item":"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/","nextItem":{"@type":"ListItem","@id":"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/european-made-saxes\/#listItem","name":"European-Made Saxes"},"previousItem":{"@type":"ListItem","@id":"https:\/\/bassic-sax.info\/version5#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/european-made-saxes\/#listItem","position":3,"name":"European-Made Saxes","item":"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/european-made-saxes\/","nextItem":{"@type":"ListItem","@id":"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/european-made-saxes\/dorfler-jorka\/#listItem","name":"D\u00f6rfler &#038; J\u00f6rka"},"previousItem":{"@type":"ListItem","@id":"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/#listItem","name":"Vintage Saxes"}},{"@type":"ListItem","@id":"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/european-made-saxes\/dorfler-jorka\/#listItem","position":4,"name":"D\u00f6rfler &#038; J\u00f6rka","item":"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/european-made-saxes\/dorfler-jorka\/","nextItem":{"@type":"ListItem","@id":"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/european-made-saxes\/dorfler-jorka\/dj-stencil-galleries\/#listItem","name":"D&#038;J Stencil Galleries"},"previousItem":{"@type":"ListItem","@id":"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/european-made-saxes\/#listItem","name":"European-Made Saxes"}},{"@type":"ListItem","@id":"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/european-made-saxes\/dorfler-jorka\/dj-stencil-galleries\/#listItem","position":5,"name":"D&#038;J Stencil Galleries","item":"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/european-made-saxes\/dorfler-jorka\/dj-stencil-galleries\/","nextItem":{"@type":"ListItem","@id":"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/european-made-saxes\/dorfler-jorka\/dj-stencil-galleries\/impala\/#listItem","name":"Impala"},"previousItem":{"@type":"ListItem","@id":"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/european-made-saxes\/dorfler-jorka\/#listItem","name":"D\u00f6rfler &#038; J\u00f6rka"}},{"@type":"ListItem","@id":"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/european-made-saxes\/dorfler-jorka\/dj-stencil-galleries\/impala\/#listItem","position":6,"name":"Impala","previousItem":{"@type":"ListItem","@id":"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/european-made-saxes\/dorfler-jorka\/dj-stencil-galleries\/#listItem","name":"D&#038;J Stencil Galleries"}}]},{"@type":"Organization","@id":"https:\/\/bassic-sax.info\/version5\/#organization","name":"Bassic Sax Studios","description":"Bassically A Site About All Things Sax","url":"https:\/\/bassic-sax.info\/version5\/","logo":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/bassic-sax.info\/version5\/wp-content\/uploads\/2025\/08\/Bassic-Sax-Logo-2025-500px.png?fit=500%2C500&ssl=1","@id":"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/european-made-saxes\/dorfler-jorka\/dj-stencil-galleries\/impala\/#organizationLogo","width":500,"height":500,"caption":"Bassic Sax log, transparent background, blue circle around blue triangle with two bass saxophones entwined around each other, Bassic Sax in a bold sans font typed under the base of the triangle"},"image":{"@id":"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/european-made-saxes\/dorfler-jorka\/dj-stencil-galleries\/impala\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/bassic.sax.blog.and.jazz.ensemble"]},{"@type":"WebPage","@id":"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/european-made-saxes\/dorfler-jorka\/dj-stencil-galleries\/impala\/#webpage","url":"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/european-made-saxes\/dorfler-jorka\/dj-stencil-galleries\/impala\/","name":"Impala - Bassic Sax | Bassic Sax","description":"Impala, D\u00f6rfler & J\u00f6rka, D&J German-made, stencil saxophone, alto sax, tenor sax, vintage saxophone, Keilwerth clone horn, not a JK stencil sax!","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/bassic-sax.info\/version5\/#website"},"breadcrumb":{"@id":"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/european-made-saxes\/dorfler-jorka\/dj-stencil-galleries\/impala\/#breadcrumblist"},"datePublished":"2010-08-28T08:28:49-07:00","dateModified":"2013-01-11T11:17:56-08:00"},{"@type":"WebSite","@id":"https:\/\/bassic-sax.info\/version5\/#website","url":"https:\/\/bassic-sax.info\/version5\/","name":"Bassic Sax","description":"Bassically A Site About All Things Sax","inLanguage":"en-US","publisher":{"@id":"https:\/\/bassic-sax.info\/version5\/#organization"}}]}},"aioseo_meta_data":{"post_id":"3249","title":"Impala - Bassic Sax | #site_title","description":"Impala, D\u00f6rfler &amp; J\u00f6rka, D&amp;J German-made, stencil saxophone, alto sax, tenor sax, vintage saxophone, Keilwerth clone horn, not a JK stencil sax!","keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-13 17:18:38","updated":"2025-06-18 23:10:08","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/bassic-sax.info\/version5\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/\" title=\"Vintage Saxes\">Vintage Saxes<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/european-made-saxes\/\" title=\"European-Made Saxes\">European-Made Saxes<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/european-made-saxes\/dorfler-jorka\/\" title=\"D\u00f6rfler &amp; J\u00f6rka\">D\u00f6rfler &amp; J\u00f6rka<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/european-made-saxes\/dorfler-jorka\/dj-stencil-galleries\/\" title=\"D&amp;J Stencil Galleries\">D&amp;J Stencil Galleries<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tImpala\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/bassic-sax.info\/version5"},{"label":"Vintage Saxes","link":"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/"},{"label":"European-Made Saxes","link":"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/european-made-saxes\/"},{"label":"D\u00f6rfler &#038; J\u00f6rka","link":"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/european-made-saxes\/dorfler-jorka\/"},{"label":"D&#038;J Stencil Galleries","link":"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/european-made-saxes\/dorfler-jorka\/dj-stencil-galleries\/"},{"label":"Impala","link":"https:\/\/bassic-sax.info\/version5\/vintage-saxes\/european-made-saxes\/dorfler-jorka\/dj-stencil-galleries\/impala\/"}],"jetpack_shortlink":"https:\/\/wp.me\/P30OPe-Qp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bassic-sax.info\/version5\/wp-json\/wp\/v2\/pages\/3249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassic-sax.info\/version5\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bassic-sax.info\/version5\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bassic-sax.info\/version5\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bassic-sax.info\/version5\/wp-json\/wp\/v2\/comments?post=3249"}],"version-history":[{"count":0,"href":"https:\/\/bassic-sax.info\/version5\/wp-json\/wp\/v2\/pages\/3249\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/bassic-sax.info\/version5\/wp-json\/wp\/v2\/pages\/1107"}],"wp:attachment":[{"href":"https:\/\/bassic-sax.info\/version5\/wp-json\/wp\/v2\/media?parent=3249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}